{"id":4203,"date":"2015-09-15T18:40:48","date_gmt":"2015-09-15T16:40:48","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4203"},"modified":"2024-01-30T09:31:34","modified_gmt":"2024-01-30T08:31:34","slug":"quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/","title":{"rendered":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?"},"content":{"rendered":"<p>Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria.<\/p>\n<p>Il rischio di frattura aumenta con il numero dei fattori di rischio.<\/p>\n<p><strong>Fattori di rischio modificabili:<\/strong><\/p>\n<p>\u2022 Abuso di bevande alcoliche<\/p>\n<p>\u2022 Fumo<\/p>\n<p>\u2022 Abuso di caff\u00e8<\/p>\n<p>\u2022 Scarsa attivit\u00e0 fisica<\/p>\n<p>\u2022 Alimentazione povera di calcio<\/p>\n<p>\u2022 Vita sedentaria<\/p>\n<p>\u2022 Carenza di calcio\/vitamina D<\/p>\n<p>\u2022 Periodi prolungati di amenorrea.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Malattie predisponenti:<\/strong><\/p>\n<p>\u2022 Ipertireosi<\/p>\n<p>\u2022 Malassorbimento (celiachia, resezioni intestinali, insufficienza pancreatica, intolleranza al lattosio)<\/p>\n<p>\u2022 Malattie intestinali infiammatorie (M. di Crohn, Colite ulcerosa)<\/p>\n<p>\u2022 Malattie reumatiche infiammatorie (artrite reumatoide, collagenosi, Bechterew)<\/p>\n<p>\u2022 Insufficienza renale cronica<\/p>\n<p>\u2022 Malattie croniche del fegato<\/p>\n<p>\u2022 Broncopneumopatia cronico-ostruttiva<\/p>\n<p>\u2022 Iperparatiroidismo<\/p>\n<p>\u2022 Diabete mellito<\/p>\n<p>\u2022 Anoressia nervosa<\/p>\n<p>\u2022 Ipercalciuria<\/p>\n<p>\u2022 Mieloma<\/p>\n<p>\u2022 Trapianto d\u2019organo<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Farmaci a rischio:<\/strong><\/em><\/p>\n<p>\u2022 Cortisone<\/p>\n<p>\u2022 Ormoni tiroidei a dosi soppressive<\/p>\n<p>\u2022 Diuretici dell\u2019ansa<\/p>\n<p>\u2022 Eparina (anticoagulante), se assunta a lungo termine e cumarinici<\/p>\n<p>\u2022 Metotrexate (un farmaco per la cura dell\u2019artrite reumatoide)<\/p>\n<p>\u2022 Alcuni farmaci antiepilettici<\/p>\n<p>\u2022 Alcuni antiacidi (contenenti alluminio)<\/p>\n<p>\u2022 Litio<\/p>\n<p>\u2022 Inibitori dell\u2019aromatasi nel trattamento ormonale del carcinoma della mammella (Arimidex\u00ae, Femara\u00ae, Aromasin\u00ae) e della prostata (Decapeptyl\u00ae, Enantone\u00ae,\u2026.)<\/p>\n<p>\u2022 Chemioterapici<\/p>","protected":false},"excerpt":{"rendered":"<p>Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa<\/p>","protected":false},"author":3,"featured_media":4204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,85],"tags":[271,272,110],"class_list":["post-4203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-osteoporosi","tag-cortisone","tag-fattori-di-rischio","tag-osteoporosi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-15T16:40:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#blogposting\",\"name\":\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project\",\"headline\":\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/osteoporosi_gibbo_vedova_Dollarphotoclub-scaled-1.jpg\",\"width\":1919,\"height\":2560},\"datePublished\":\"2015-09-15T18:40:48+02:00\",\"dateModified\":\"2024-01-30T09:31:34+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#webpage\"},\"articleSection\":\"Blog, Osteoporosi, cortisone, fattori di rischio, osteoporosi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#listItem\",\"name\":\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#listItem\",\"position\":3,\"name\":\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/\",\"name\":\"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project\",\"description\":\"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\\u2019et\\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \\u2022 Abuso di bevande\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/osteoporosi_gibbo_vedova_Dollarphotoclub-scaled-1.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#mainImage\",\"width\":1919,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/15\\\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\\\/#mainImage\"},\"datePublished\":\"2015-09-15T18:40:48+02:00\",\"dateModified\":\"2024-01-30T09:31:34+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project","description":"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande","canonical_url":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#blogposting","name":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project","headline":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?","author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/osteoporosi_gibbo_vedova_Dollarphotoclub-scaled-1.jpg","width":1919,"height":2560},"datePublished":"2015-09-15T18:40:48+02:00","dateModified":"2024-01-30T09:31:34+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#webpage"},"articleSection":"Blog, Osteoporosi, cortisone, fattori di rischio, osteoporosi"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/de\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#listItem","name":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#listItem","position":3,"name":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/de\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#webpage","url":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/","name":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project","description":"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/osteoporosi_gibbo_vedova_Dollarphotoclub-scaled-1.jpg","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#mainImage","width":1919,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/#mainImage"},"datePublished":"2015-09-15T18:40:48+02:00","dateModified":"2024-01-30T09:31:34+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/de\/#website","url":"https:\/\/toplifeproject.com\/de\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"de-DE","publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project","og:description":"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande","og:url":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2015-09-15T16:40:48+00:00","article:modified_time":"2024-01-30T08:31:34+00:00","twitter:card":"summary_large_image","twitter:title":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO? - Top Life Project","twitter:description":"Distinguiamo principalmente 2 forme di osteoporosi: quella dopo la menopausa e dell\u2019et\u00e0 avanzata che chiamiamo primitiva (o rispettivamente post-menopausale e senile) e quella causata da altre patologie o dall\u2019assunzione di particolari farmaci che chiamiamo secondaria. Il rischio di frattura aumenta con il numero dei fattori di rischio. Fattori di rischio modificabili: \u2022 Abuso di bevande","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4203","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:18:56","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:07:02","updated":"2026-05-12 21:18:56","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tQUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/de"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/de\/category\/blog\/"},{"label":"QUALI TIPI DI OSTEOPOROSI CONOSCIAMO? QUALI I FATTORI DI RISCHIO?","link":"https:\/\/toplifeproject.com\/de\/2015\/09\/15\/quali-tipi-di-osteoporosi-conosciamo-quali-i-fattori-di-rischio\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-03 14:10:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/comments?post=4203"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media\/4204"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media?parent=4203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/categories?post=4203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/tags?post=4203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}