{"id":4260,"date":"2015-09-26T16:47:01","date_gmt":"2015-09-26T14:47:01","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4260"},"modified":"2024-01-30T09:31:33","modified_gmt":"2024-01-30T08:31:33","slug":"i-grassi-la-realta-i-miti-gli-interessi-economici","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/","title":{"rendered":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI"},"content":{"rendered":"<p><u><\/u><em>Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura,<\/em><\/p>\n<p><em>Jonathan Swift<\/em><\/p>\n<p>I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta, sia materiale per la formazione di membrane cellulari, ormoni e sostanze ormono-simili. Se fanno parte di un pasto riducono la velocit\u00e0 di assorbimento di altri alimenti, diminuendo il nostro senso di fame. Essi garantiscono l\u2019assorbimento delle importanti vitamine liposolubili A, D, E e K. I grassi sono necessari per convertire il carotene in vitamina A, per assorbire i minerali e per molteplici altri processi che andremo ad esaminare.<\/p>\n<p>Le indicazioni dietetiche dettate dalle cosiddette linee guida ufficiali si basano sulla teoria che dobbiamo ridurre l\u2019introito di grassi, specie quelli sauri di origine animale, che contengono colesterolo, additato come il cattivo della dieta civilizzata. Mai come negli ultimi trent\u2019anni abbiamo ridotto a livello mondiale il consumo di grassi saturi, e mai, come adesso, siamo stati cos\u00ec malati; basti pensare ai numeri vertiginosi di obesit\u00e0, infarto, ictus, diabete, ipertensione arteriosa, demenza, Alzheimer, cancro, osteoporosi, carie, gastrite,\u2026\u2026..abbiamo sostituito il consumo di grassi sani con un consumo abnorme di carboidrati raffinati associati a olii vegetali polinsaturi in ogni forma: pasta, cracker, grissini, biscotti, torte, pizze, brioches, merendine, ecc.<\/p>\n<p>Purtroppo per decenni ci \u00e8 stato detto che i grassi saturi sono nocivi, e che per noi vanno meglio i grassi polinsaturi. Ed \u00e8 a questa informazione errata che dobbiamo i grandi cambiamenti avvenuti nella nostra alimentazione nel corso degli ultimi decenni. All\u2019inizio del 900 la maggior parte dei grassi assunti erano saturi o monoinsaturi, principalmente provenienti da burro, lardo, olio di cocco, e meno olio di oliva. Oggigiorno la maggior parte dei grassi nella dieta sono polinsaturi, prevalentemente di provenienza vegetale come soia, mais, girasole e colza. Le diete moderne contengono fino al 30% dell\u2019apporto calorico in forma di grassi polinsaturi, e questa quantit\u00e0 \u00e8 certamente troppo alta!! Noi non dovremmo assumere pi\u00f9 del 4% di grassi polinsaturi, di cui l\u20191,5% di omega3 e il 2,5% di omega 6. Un tale rapporto ottimale lo troviamo in popolazioni native, in cui la fonte di questi grassi polinsaturi proviene da legumi, noci, grano, verdura verde, pesce, olio di oliva e grasso animale, e non dagli oli raffinati industrialmente che purtroppo caratterizzano la nostra alimentazione.<\/p>\n<p>I grassi o lipidi sono una categoria di sostanze organiche formate da catene di atomi di carbonio con atomi d\u2019idrogeno che riempiono i legami scoperti. Tutti i grassi naturali, sia di origine vegetale che animale, sono una miscela di acidi grassi saturi (nessun doppio legame tra gli atomi di carbonio), monoinsaturi (un unico doppio legame; tipico esempio l\u2019acido oleico, che costituisce il 73% dei grassi contenuti nell\u2019olio di oliva extravergine) e polinsaturi (due o pi\u00f9 doppi legami tra gli atomi di carbonio, e quindi meno atomi di idrogeno). In genere i grassi animali come il burro e il lardo contengono il 40-60% di grassi saturi e sono solidi. Gli oli vegetali contengono prevalentemente acidi grassi polinsaturi e sono liquidi, a differenza degli oli vegetali tropicali che sono prevalentemente saturi: l\u2019olio di cocco contiene, infatti, il 92% di acidi grassi saturi.<\/p>","protected":false},"excerpt":{"rendered":"<p>Oltre le malattie reali siamo vittime di molte malattie immaginarie,<\/p>","protected":false},"author":3,"featured_media":4261,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,92],"tags":[299,300],"class_list":["post-4260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-grassi-buoni-o-cattivi-e-colesterolo","tag-grassi","tag-grassi-animali"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-26T14:47:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#blogposting\",\"name\":\"I GRASSI: LA REALT\\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project\",\"headline\":\"I GRASSI: LA REALT\\u00c0, I MITI, GLI INTERESSI ECONOMICI\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/149-category.jpg\",\"width\":500,\"height\":250},\"datePublished\":\"2015-09-26T16:47:01+02:00\",\"dateModified\":\"2024-01-30T09:31:33+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#webpage\"},\"articleSection\":\"Blog, Grassi: Buoni o Cattivi e Colesterolo, grassi, grassi animali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#listItem\",\"name\":\"I GRASSI: LA REALT\\u00c0, I MITI, GLI INTERESSI ECONOMICI\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#listItem\",\"position\":3,\"name\":\"I GRASSI: LA REALT\\u00c0, I MITI, GLI INTERESSI ECONOMICI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/\",\"name\":\"I GRASSI: LA REALT\\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project\",\"description\":\"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/149-category.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#mainImage\",\"width\":500,\"height\":250},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2015\\\/09\\\/26\\\/i-grassi-la-realta-i-miti-gli-interessi-economici\\\/#mainImage\"},\"datePublished\":\"2015-09-26T16:47:01+02:00\",\"dateModified\":\"2024-01-30T09:31:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project","description":"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,","canonical_url":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#blogposting","name":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project","headline":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI","author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/149-category.jpg","width":500,"height":250},"datePublished":"2015-09-26T16:47:01+02:00","dateModified":"2024-01-30T09:31:33+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#webpage"},"articleSection":"Blog, Grassi: Buoni o Cattivi e Colesterolo, grassi, grassi animali"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/de\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#listItem","name":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#listItem","position":3,"name":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/de\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#webpage","url":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/","name":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project","description":"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/149-category.jpg","@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#mainImage","width":500,"height":250},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/#mainImage"},"datePublished":"2015-09-26T16:47:01+02:00","dateModified":"2024-01-30T09:31:33+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/de\/#website","url":"https:\/\/toplifeproject.com\/de\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"de-DE","publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project","og:description":"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,","og:url":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2015-09-26T14:47:01+00:00","article:modified_time":"2024-01-30T08:31:33+00:00","twitter:card":"summary_large_image","twitter:title":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI - Top Life Project","twitter:description":"Oltre le malattie reali siamo vittime di molte malattie immaginarie, per le quali i medici hanno inventato cure immaginarie dai molti nomi, le quali, a loro volta, hanno svariati nomi, come le medicine adatte alla loro cura, Jonathan Swift I grassi di origine animale e vegetale forniscono sia un notevole apporto energetico alla nostra dieta,","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4260","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:27:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:08:21","updated":"2026-05-12 21:27:15","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tI GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/de"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/de\/category\/blog\/"},{"label":"I GRASSI: LA REALT\u00c0, I MITI, GLI INTERESSI ECONOMICI","link":"https:\/\/toplifeproject.com\/de\/2015\/09\/26\/i-grassi-la-realta-i-miti-gli-interessi-economici\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:15:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/comments?post=4260"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media\/4261"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media?parent=4260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/categories?post=4260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/tags?post=4260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}