{"id":4305,"date":"2020-01-02T11:14:38","date_gmt":"2020-01-02T10:14:38","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4305"},"modified":"2024-01-30T09:31:31","modified_gmt":"2024-01-30T08:31:31","slug":"colesterolo-hdl-e-trigliceridi-occhio-al-rapporto","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/","title":{"rendered":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto"},"content":{"rendered":"<p><strong><span style=\"color: #ff0000;\">Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca.<\/span><\/strong><\/p>\n<p>Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL).<\/p>\n<p>O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL:<br \/>\n\u2022 2 \u2013 ideale<br \/>\n\u2022 4 \u2013 elevato<br \/>\n\u2022 6 \u2013 troppo elevato.<\/p>\n<p>E, poich\u00e9 il colesterolo HDL (lipoproteina ad alta densit\u00e0) \u00e8 protettivo contro le malattie cardiache, pi\u00f9 basso il rapporto, migliore \u00e8 la prognosi (cio\u00e8 l\u2019aspettativa di vita senza attacchi cardiaci).<br \/>\nIn altre parole, pi\u00f9 bassi sono i tuoi trigliceridi, o pi\u00f9 alto il tuo HDL, pi\u00f9 piccolo diventa questo rapporto.<br \/>\nUn autore di un importante studio di Harvard ha affermato: \u201cI trigliceridi elevati, da soli, aumentato il rischio di attacco cardiaco quasi del triplo. E i soggetti con il pi\u00f9 alto rapporto di trigliceridi \/ colesterolo HDL \u2013 il colesterolo \u201cbuono\u201d \u2013 avevano 16 volte il rischio di attacco cardiaco, rispetto a quelli con il rapporto pi\u00f9 basso di trigliceridi \/ colesterolo HDL, nello studio in cui erano stati esaminati 340 pazienti con infarto e 340 loro controparti sane e della stessa et\u00e0\u201d.<br \/>\nQuesto studio, ha concluso: il rapporto fra trigliceridi e colesterolo HDL \u00e8 il pi\u00f9 importante indice di rischio di un attacco di cuore, ancora pi\u00f9 accurato rispetto il rapporto colesterolo LDL\/HDL.<\/p>","protected":false},"excerpt":{"rendered":"<p>Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei<\/p>","protected":false},"author":3,"featured_media":4306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,92],"tags":[93,163,186,185,187],"class_list":["post-4305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-grassi-buoni-o-cattivi-e-colesterolo","tag-colesterolo","tag-colesterolo-hdl","tag-ldl","tag-rapporto","tag-rischio-cardiovascolare"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-02T10:14:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#blogposting\",\"name\":\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project\",\"headline\":\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/screen-HP-pipette-trigliceridi-858x442_c.jpg\",\"width\":858,\"height\":442},\"datePublished\":\"2020-01-02T11:14:38+01:00\",\"dateModified\":\"2024-01-30T09:31:31+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#webpage\"},\"articleSection\":\"Blog, Grassi: Buoni o Cattivi e Colesterolo, Colesterolo, colesterolo HDL, LDL, rapporto, rischio cardiovascolare\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#listItem\",\"name\":\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#listItem\",\"position\":3,\"name\":\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/\",\"name\":\"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project\",\"description\":\"Oggi si ritiene che il rapporto trigliceridi\\\/HDL sia uno dei pi\\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\\\/HDL-colesterolo \\u201cbuono\\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\\u00f9 precisamente, il rapporto trigliceridi\\\/HDL: \\u2022 2 \\u2013 ideale \\u2022 4 \\u2013 elevato \\u2022\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/screen-HP-pipette-trigliceridi-858x442_c.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#mainImage\",\"width\":858,\"height\":442},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\\\/#mainImage\"},\"datePublished\":\"2020-01-02T11:14:38+01:00\",\"dateModified\":\"2024-01-30T09:31:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project","description":"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022","canonical_url":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#blogposting","name":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project","headline":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto","author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/screen-HP-pipette-trigliceridi-858x442_c.jpg","width":858,"height":442},"datePublished":"2020-01-02T11:14:38+01:00","dateModified":"2024-01-30T09:31:31+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#webpage"},"articleSection":"Blog, Grassi: Buoni o Cattivi e Colesterolo, Colesterolo, colesterolo HDL, LDL, rapporto, rischio cardiovascolare"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/de\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#listItem","name":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#listItem","position":3,"name":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/de\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#webpage","url":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/","name":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project","description":"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/screen-HP-pipette-trigliceridi-858x442_c.jpg","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#mainImage","width":858,"height":442},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/#mainImage"},"datePublished":"2020-01-02T11:14:38+01:00","dateModified":"2024-01-30T09:31:31+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/de\/#website","url":"https:\/\/toplifeproject.com\/de\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"de-DE","publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project","og:description":"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022","og:url":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2020-01-02T10:14:38+00:00","article:modified_time":"2024-01-30T08:31:31+00:00","twitter:card":"summary_large_image","twitter:title":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto - Top Life Project","twitter:description":"Oggi si ritiene che il rapporto trigliceridi\/HDL sia uno dei pi\u00f9 potenti indici predittivi di malattia cardiaca. Negli adulti, il rapporto trigliceridi\/HDL-colesterolo \u201cbuono\u201d dovrebbe essere inferiore a 2 (basta dividere il livello dei tuoi trigliceridi per il tuo colesterolo HDL). O pi\u00f9 precisamente, il rapporto trigliceridi\/HDL: \u2022 2 \u2013 ideale \u2022 4 \u2013 elevato \u2022","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4305","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:45:32","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:15:13","updated":"2026-05-12 21:45:32","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tCOLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/de"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/de\/category\/blog\/"},{"label":"COLESTEROLO HDL E TRIGLICERIDI: occhio al rapporto","link":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/colesterolo-hdl-e-trigliceridi-occhio-al-rapporto\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:11:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/comments?post=4305"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media\/4306"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media?parent=4305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/categories?post=4305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/tags?post=4305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}