{"id":4680,"date":"2016-02-24T23:14:21","date_gmt":"2016-02-24T22:14:21","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4680"},"modified":"2024-01-30T09:31:33","modified_gmt":"2024-01-30T08:31:33","slug":"lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/","title":{"rendered":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;."},"content":{"rendered":"<p>Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi.<\/p>\n<p>L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie, in quanto potrebbero soffrire di enorme aumento di peso.<\/p>\n<p>Continua dicendo che \u201cnon c\u2019\u00e8 evidenza scientifica\u201d che le diete LCHF abbiano successo, mostrando cos\u00ec di ignorare che ci sono almeno 19 studi di alta evidenza scientifica (parliamo di RCT) su umani che mostrano inequivocabilmente che le diete a basso contenuto di zuccheri non solo sono efficaci, ma lo sono in modo significantemente superiore rispetto alle altre diete.<\/p>\n<p>Vi specifico che i summenzionati studi vengono fatti su umani mentre lo studio di Andrikopoulos viene fatto su topi, una specie che sappiamo non adatta ad una dieta ad alto tenore di grassi!!!! Non \u00e8 certo una novit\u00e0 che i topo ingrassano mangiando grasso, mentre gli umani dimagriscono se seguono un\u2019alimentazione LCHF!<\/p>\n<p>Ritengo non ci sia da aggiungere altro sul tema, solo forse una constatazione: \u00e8 veramente triste che i media saltino a conclusioni completamente errate, senza valutarne la veridict\u00e0 e le divulghino come verit\u00e0 inconfutabili.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mi \u00e8 stato chiesto che cosa ne penso dello studio<\/p>","protected":false},"author":3,"featured_media":4575,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,72,77,78,79],"tags":[290,288,289],"class_list":["post-4680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentazione","category-blog","category-dieta","category-metabolismo","category-obesita","tag-obesi","tag-paleo","tag-topi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-24T22:14:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#blogposting\",\"name\":\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\\u2026..I TOPI\\u2026\\u2026. - Top Life Project\",\"headline\":\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;.\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Paleo_Lebensmittel.jpg\",\"width\":1000,\"height\":662},\"datePublished\":\"2016-02-24T23:14:21+01:00\",\"dateModified\":\"2024-01-30T09:31:33+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#webpage\"},\"articleSection\":\"Alimentazione, Blog, Dieta, Metabolismo, Obesit\\u00e0, obesi, paleo, topi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#listItem\",\"name\":\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#listItem\",\"position\":3,\"name\":\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/\",\"name\":\"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\\u2026..I TOPI\\u2026\\u2026. - Top Life Project\",\"description\":\"Mi \\u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Paleo_Lebensmittel.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#mainImage\",\"width\":1000,\"height\":662},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2016\\\/02\\\/24\\\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\\\/#mainImage\"},\"datePublished\":\"2016-02-24T23:14:21+01:00\",\"dateModified\":\"2024-01-30T09:31:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project","description":"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,","canonical_url":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#blogposting","name":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project","headline":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;.","author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/Paleo_Lebensmittel.jpg","width":1000,"height":662},"datePublished":"2016-02-24T23:14:21+01:00","dateModified":"2024-01-30T09:31:33+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#webpage"},"articleSection":"Alimentazione, Blog, Dieta, Metabolismo, Obesit\u00e0, obesi, paleo, topi"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/de\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#listItem","name":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;."},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#listItem","position":3,"name":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;.","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/de\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#webpage","url":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/","name":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project","description":"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/Paleo_Lebensmittel.jpg","@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#mainImage","width":1000,"height":662},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/#mainImage"},"datePublished":"2016-02-24T23:14:21+01:00","dateModified":"2024-01-30T09:31:33+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/de\/#website","url":"https:\/\/toplifeproject.com\/de\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"de-DE","publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project","og:description":"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,","og:url":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2016-02-24T22:14:21+00:00","article:modified_time":"2024-01-30T08:31:33+00:00","twitter:card":"summary_large_image","twitter:title":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026. - Top Life Project","twitter:description":"Mi \u00e8 stato chiesto che cosa ne penso dello studio che afferma che la paleo-dieta fa venire il diabete e rende obesi. L\u2019autore, Professore associato Sof Andrikopoulos, afferma che probabilmente lo studio dice che la gente dovrebbe evitare diete paleo a basso contenuto di zuccheri ed alto contenuto di grassi, specie persone obese e sedentarie,","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4680","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:31:53","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:13:03","updated":"2026-05-12 21:31:53","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tLO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI\u2026..I TOPI\u2026\u2026.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/de"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/de\/category\/blog\/"},{"label":"LO STUDIO CHE AFFERMA CHE LA PALEODIETA RENDE OBESI E DIABETICI&#8230;..I TOPI&#8230;&#8230;.","link":"https:\/\/toplifeproject.com\/de\/2016\/02\/24\/lo-studio-che-afferma-che-la-paleodieta-rende-obesi-e-diabetici-i-topi\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:08:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/comments?post=4680"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media\/4575"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media?parent=4680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/categories?post=4680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/tags?post=4680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}