{"id":4865,"date":"2020-01-02T10:41:15","date_gmt":"2020-01-02T09:41:15","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4865"},"modified":"2024-01-30T09:31:31","modified_gmt":"2024-01-30T08:31:31","slug":"non-riesci-piu-a-perdere-peso-ti-spiego-perche","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/","title":{"rendered":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8"},"content":{"rendered":"<p>Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati?<\/p>\n<p>Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l&#8217;et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato la frustrazione di un metabolismo lento. Anche voi?<\/p>\n<p>Sappiamo che stare a dieta pu\u00f2 essere estenuante. La necessit\u00e0 di una disciplina costante, la limitazione delle opzioni alimentari e la sensazione di deprivazione possono uccidere la motivazione. \u00c8 comprensibile desiderare una soluzione rapida con una pillola o un piano dietetico che promette risultati in una notte. In realt\u00e0, la sfida con la perdita di peso a lungo termine \u00e8 molto pi\u00f9 profonda.<\/p>\n<p>\u2699\ufe0f\u00a0Un punto fondamentale che manca nei discorsi che noi medici o professionisti del settore facciamo con voi sulla perdita di peso \u00e8 la connessione tra il cervello e il corpo. Quando non riusciamo ad affrontare il modo in cui il nostro cervello influenza il nostro corpo, programmiamo un sicuro fallimento, perch\u00e9 il cervello influenza non solo il nostro obiettivo di riferimento del peso, ma anche il nostro umore, l&#8217;energia e la motivazione per avere successo.<\/p>\n<p>Ci scordiamo che, non di rado, mangiare \u00e8 una compensazione, un premio, uno sfogo: tutti motivi che non dovrebbero avere nulla a che fare col cibo, ma che, spesso, troppo spesso, ne sono collegati.<\/p>\n<p>?\u00a0Ammettiamolo, perdere peso \u00e8 di solito un&#8217;esperienza terribile. Dopo aver fatto progressi, dopo aver visto i primi cambiamenti positivi del corpo e felici perch\u00e8 cominciamo ad entrare nei pantaloni che ci erano costati un rene, zac: il peso resta fermo l\u00ec.<\/p>\n<p>\u2753Perch\u00e9 succede questo? Cosa dobbiamo fare per superare questa &#8220;frenata&#8221;?<\/p>\n<p>?\u00a0Ora vi spiego cosa potete fare quando arriva l&#8217;inevitabile plateau.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff00ff;\"><strong>L&#8217;insulina \u00e8 il custode del vostro metabolismo<\/strong><\/span><\/h3>\n<p>A nessuna di noi piace sentirsi affamata, stanca, fiacca o senza energie.\u00a0 In genere, questi sintomi si manifestano quando l&#8217;insulina nel nostro corpo non funziona bene.\u00a0 Il nostro sistema diventa sbilanciato dallo stress, da una dieta scorretta e da uno stile di vita sempre di corsa.<\/p>\n<p>L&#8217;insulina \u00e8 l\u2019ormone che regola la glicemia ed influisce sul nostro umore, sui pensieri, sulle prestazioni e sull&#8217;accumulo di grassi.\u00a0 La perdita di peso \u00e8 molto pi\u00f9 facile se bilanciamo l&#8217;insulina. L\u2019insulina \u00e8 la custode del nostro metabolismo. Quando l&#8217;insulina \u00e8 bilanciata e funziona correttamente, vedrai che riuscirai a perdere peso. Come fare per bilanciarla? Semplice: taglia i carboidrati e muoviti!!!<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff00ff;\"><strong>Rigenerare la tiroide<\/strong><\/span><\/h3>\n<p>Questa minuscola ghiandola gioca un ruolo cruciale in molte funzioni ormonali nel cervello e nel corpo.\u00a0 In particolare il T3, che \u00e8 l\u2019ormone tiroideo attivo \u00e8 una delle chiavi per aiutarci a perdere o aumentare di peso. Il T3 viene convertito dall&#8217;ormone T4 e per farlo il nostro corpo ha bisogno dei giusti nutrienti , senn\u00f2 la tiroide rallenta e anche la nostra perdita di peso.<\/p>\n<p>Se mangiamo zucchero, cibi spazzatura (anche tutte quelle schifezze con cui vi siete rimpinzate in questi giorni come biscotti, panettone, tortine, desserts vari\u2026\u2026..), o abbiamo una tiroidite, la produzione di ormoni tiroidei rallenta.<\/p>\n<p>Cosa fare? Ma \u00e8 semplice: diamo alla tiroide le giuste sostanze nutritive; selenio, zinco, vitamina D, magnesio, inositolo. Via le schifezze dalla nostra tavola e vedrete che la tiroide sar\u00e0 in grado di riprendere la sua funzione\u00a0 positiva per il nostro metabolismo.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff00ff;\"><strong>Regolare il cortisolo controllando lo stress<\/strong><\/span><\/h3>\n<p>Sappiamo bene che lo stress provoca l&#8217;infiammazione, che causa una serie di problemi di salute.\u00a0 Pensa a quando ti senti il viso un po&#8217; gonfio, le articolazioni rigide o il cervello appannato. Questa \u00e8 un&#8217;infiammazione. Crea scompiglio nel nostro cervello e nel nostro corpo.\u00a0 Negli anni questa infiammazione cronica crea problemi a livello arterioso, sbilancia la composizione del nostro microbioma intestinale, influenza il nostro umore e col passare degli anni, ne risentiamo\u2026\u2026.anche al girovita.<\/p>\n<p>Cosa fare?<\/p>\n<p>Importante \u00e8 dormire: ma ne parler\u00f2 in un articolo dedicato. Poi abbiamo due integratori splendidi che ci possono aiutare a ridurre lo stress: \u00a0gli Omega-3 e la rodiola. Entrambi hanno il potere di ridurre lo stress sia mentalmente che nel nostro corpo. Credetemi: non esiste un farmaco in grado di farlo senza una triste lista di effetti collaterali.<\/p>\n<p><em><strong>Gli Omega-3<\/strong><\/em> riducono l&#8217;infiammazione e migliorano la nostra salute cardiovascolare.\u00a0Questo riduce i tassi di malattie cardiache, demenza, artrite e depressione. Il corpo non pu\u00f2 fare Omega-3 da solo, quindi dobbiamo assumerli col cibo o con un integratore.\u00a0 Contribuiscono alla perdita di peso e migliorano la funzione cerebrale: ottimi per l\u2019umore!<\/p>\n<p>La <em><strong>rodiola<\/strong><\/em> regola il cortisolo, lo stress mentale e allevia il burnout.\u00a0 \u00c8 in grado di ridurre sia l&#8217;ansia che la fiacchezza. Inoltre, \u00e8 un&#8217;erba \u201cadattogena\u201d che aiuta il vostro corpo per aiutare qualsiasi ormone carente.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong><span style=\"color: #ff00ff;\">La vitamina D<\/span> <\/strong><\/h3>\n<p>La vitamina D svolge un ruolo vitale nella regolazione ormonale.\u00a0Bassi livelli contribuiscono a rallentare la funzione tiroidea e altri disturbi ormonali.\u00a0 Aiuta l&#8217;assorbimento del calcio e dei minerali che rafforzano il nostro sistema immunitario e sostengono la salute di ossa e denti.<\/p>\n<p>La vitamina D \u00e8 anche la chiave per mantenere una connessione armoniosa tra corpo e cervello.\u00a0 La maggior parte delle vitamine e delle sostanze nutritive non possono essere assorbite dal nostro organismo senza la contemporanea presenza di altri importanti micronutrienti.\u00a0 Tutto si interconnette tra il nostro cervello e il corpo; nessuna cellula opera in modo isolato.<\/p>\n<p>La vitamina D ci aiuta anche raggiungere il nostro peso, sostenendo la tiroide nella produzione ormonale.<\/p>\n<p>Come pu\u00f2\u00a0 la vitamina D favorire la perdita di peso?<\/p>\n<p>Quando i livelli di vitamina D nel sangue sono bassi, pu\u00f2 essere pi\u00f9 difficile dimagrire.<\/p>\n<p>Questo perch\u00e9 il grasso corporeo in eccesso assorbe la vitamina D, impedendogli di entrare nel flusso sanguigno per essere utilizzato dal corpo.<\/p>\n<p>Questa carenza interferisce anche direttamente con l&#8217;azione dell&#8217;ormone leptina, che \u00e8 responsabile di comunicare al vostro cervello che siete sazi. La conseguenza \u00e8 che si mangia troppo.<\/p>\n<p>Un recente studio australiano ha dimostrato che le persone che hanno mangiato una colazione ad alto contenuto di D e calcio, hanno ridotto il loro appetito per le prossime 24 ore.<\/p>\n<p>La carenza di vitamina D \u00e8 anche legata alla resistenza all&#8217;insulina, che porta alla fame e all&#8217;eccessivo introito di cibo.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff00ff;\"><strong>Sonno adeguato<\/strong><\/span><\/h3>\n<p>Conoscete gi\u00e0 l&#8217;importanza del sonno per la vostra salute. Ma sapevate che il sonno regola oltre 600 geni? Tra questi vi sono i geni della perdita di peso (come i geni CLOCK) e i geni che predicono il rischio di Alzheimer (APOE4). Ottimale \u00e8 dormire 7-8 per notte per perdere peso, perch\u00e9 se avete una variante del gene clock il risultato pu\u00f2 essere una aumento dei vostri livelli di grelina, un ormone che vi fa venire fame.<\/p>\n<p>Dormire poco e\/o male ha conseguenza dirette sulla perdita di peso. Perch\u00e9? Perch\u00e9 avrete meno leptina che blocca la fame e pi\u00f9 grelina che ve la stimola, avrete voglia di cibi dolci e continuerete a mangiare (devastanti per il vostro girovita ma anche per ipertensione, diabete, malattie cardiovascolari!). La carenza di sonno porta inoltre ad un aumento di stress con la secrezione di ormoni (cortisolo) che rallentano il metabolismo.<\/p>\n<p>E pi: lo sapevate che durante le ore di sonno bruciate molte calorie? Quindi, se dormite poche ore per notte, ne bruciate meno oltre e squilibrare tutto il resto!<\/p>\n<p>Quindi per ottenere tutti i benefici di salute e bellezza con una notte di sonno ristoratore, dormite al buio, stanza fresca, NO apparecchi elettronici (TV, cellulari, tablets) o fonti di onde elettromagnetiche nella stanza, casomai occhiali blueblocker la sera per evitare la luce blu con i suoi effetti devastanti sul blocco della produzione di melatonina, l\u2019ormone con il pi\u00f9 potente effetto antiossidante.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vi siete chieste se le modelle e le star del<\/p>","protected":false},"author":3,"featured_media":4657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,72,77,78,79],"tags":[131,106,209,70,181,188,183,208],"class_list":["post-4865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentazione","category-blog","category-dieta","category-metabolismo","category-obesita","tag-cortisolo","tag-dieta","tag-insulina","tag-omega-3","tag-perdere-peso","tag-sonno","tag-stress","tag-vitamina-d"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l&#039;et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l&#039;et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-02T09:41:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l&#039;et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#blogposting\",\"name\":\"Non riesci pi\\u00f9 a perdere peso? Ti spiego perch\\u00e8 - Top Life Project\",\"headline\":\"Non riesci pi\\u00f9 a perdere peso? Ti spiego perch\\u00e8\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/bulimia.jpg\",\"width\":624,\"height\":351},\"datePublished\":\"2020-01-02T10:41:15+01:00\",\"dateModified\":\"2024-01-30T09:31:31+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#webpage\"},\"articleSection\":\"Alimentazione, Blog, Dieta, Metabolismo, Obesit\\u00e0, cortisolo, dieta, insulina, omega 3, perdere peso, sonno, stress, vitamina D\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#listItem\",\"name\":\"Non riesci pi\\u00f9 a perdere peso? Ti spiego perch\\u00e8\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#listItem\",\"position\":3,\"name\":\"Non riesci pi\\u00f9 a perdere peso? Ti spiego perch\\u00e8\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/\",\"name\":\"Non riesci pi\\u00f9 a perdere peso? Ti spiego perch\\u00e8 - Top Life Project\",\"description\":\"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\\u00e0 di perdere peso \\u00e8 difficile per la maggior parte di noi, soprattutto con l'et\\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/bulimia.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#mainImage\",\"width\":624,\"height\":351},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/2020\\\/01\\\/02\\\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\\\/#mainImage\"},\"datePublished\":\"2020-01-02T10:41:15+01:00\",\"dateModified\":\"2024-01-30T09:31:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project","description":"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l'et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato","canonical_url":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#blogposting","name":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project","headline":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8","author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/bulimia.jpg","width":624,"height":351},"datePublished":"2020-01-02T10:41:15+01:00","dateModified":"2024-01-30T09:31:31+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#webpage"},"articleSection":"Alimentazione, Blog, Dieta, Metabolismo, Obesit\u00e0, cortisolo, dieta, insulina, omega 3, perdere peso, sonno, stress, vitamina D"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/de\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#listItem","name":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#listItem","position":3,"name":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/de\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/de\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#webpage","url":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/","name":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project","description":"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l'et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/toplifeproject.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/de\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/bulimia.jpg","@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#mainImage","width":624,"height":351},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/#mainImage"},"datePublished":"2020-01-02T10:41:15+01:00","dateModified":"2024-01-30T09:31:31+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/de\/#website","url":"https:\/\/toplifeproject.com\/de\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"de-DE","publisher":{"@id":"https:\/\/toplifeproject.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project","og:description":"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l'et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato","og:url":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2020-01-02T09:41:15+00:00","article:modified_time":"2024-01-30T08:31:31+00:00","twitter:card":"summary_large_image","twitter:title":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8 - Top Life Project","twitter:description":"Vi siete chieste se le modelle e le star del cinema conoscono dei segreti per perdere peso che a noi comuni mortali sono negati? Gli studi dimostrano che la capacit\u00e0 di perdere peso \u00e8 difficile per la maggior parte di noi, soprattutto con l'et\u00e0. La maggior parte delle donne sopra i 35 anni ha sperimentato","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4865","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:42:46","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:15:13","updated":"2026-05-12 21:42:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/de\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tNon riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/de"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/de\/category\/blog\/"},{"label":"Non riesci pi\u00f9 a perdere peso? Ti spiego perch\u00e8","link":"https:\/\/toplifeproject.com\/de\/2020\/01\/02\/non-riesci-piu-a-perdere-peso-ti-spiego-perche\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:13:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/comments?post=4865"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/posts\/4865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media\/4657"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/media?parent=4865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/categories?post=4865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/de\/wp-json\/wp\/v2\/tags?post=4865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}