{"id":4106,"date":"2018-01-03T20:26:37","date_gmt":"2018-01-03T19:26:37","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4106"},"modified":"2024-01-30T09:31:32","modified_gmt":"2024-01-30T08:31:32","slug":"gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/","title":{"rendered":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!"},"content":{"rendered":"<div id=\"js_2x\" class=\"_5pbx userContent _3576\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\">\n<div id=\"id_5a4d39359096a3003368697\" class=\"text_exposed_root text_exposed\">\n<p><em><strong><span style=\"color: #ff0000;\">Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc<\/span><\/strong><\/em><\/p>\n<p><em><strong><span style=\"color: #ff0000;\">I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali.<\/span><\/strong><\/em><\/p>\n<div class=\"text_exposed_show\">\n<p>I gastroprotettori assunti su base cronica possono causare una <strong><em><span style=\"color: #ff0000;\">carenza di vitamina B12<\/span><\/em><\/strong>, dovuta al fatto che l&#8217;assunzione di questa vitamina dal cibo dipende dall&#8217;acido presente nello stomaco che viene inibito appunto da questi farmaci. Controllate sempre i valori di vitamina B12 e folati negli esami del sangue!!!!<\/p>\n<p>Poi segue un possibile <em><strong><span style=\"color: #ff0000;\">deficit di ferro, ma anche di magnesio, potassio e calcio<\/span><\/strong><\/em>: ne possono conseguire anomalie dell&#8217;attivit\u00e0 cardiaca.<\/p>\n<p>Pensate che una meta-analisi condotta su 250.000 pazienti ha dimostrato un <em><span style=\"color: #ff0000;\"><strong>aumento del 25% delle fratture di femore e del 58% di quelle vertebrali<\/strong> <\/span><\/em>in chi utilizza cronicamente gastroprotettori.<\/p>\n<p>Anche l<span style=\"color: #ff0000;\"><em><strong>&#8216;insufficienza renale<\/strong><\/em><\/span> pu\u00f2 essere associata (anche se non ne conosciamo il meccanismo) alla loro assunzione: chi li assume ha il 45% di probabilit\u00e0 in pi\u00f9 di danno renale.<br \/>\nInoltre, una meta-analisi su 9 studi clinici controllti che includevano 120.000 pazienti ha dimostrato un aumento delle <span style=\"color: #ff0000;\"><em><strong>polmoniti<\/strong><\/em><\/span>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"_3x-2\">\n<div data-ft=\"{&quot;tn&quot;:&quot;H&quot;}\">\n<div class=\"mtm\">\n<div class=\"_5cq3\" data-ft=\"{&quot;tn&quot;:&quot;E&quot;}\"><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come<\/p>","protected":false},"author":3,"featured_media":4107,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,73],"tags":[],"class_list":["post-4106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-farmaci"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l&#039;assunzione\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l&#039;assunzione\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-01-03T19:26:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l&#039;assunzione\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#blogposting\",\"name\":\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project\",\"headline\":\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/farmaci-acidita-di-stomaco.jpg\",\"width\":400,\"height\":334},\"datePublished\":\"2018-01-03T20:26:37+01:00\",\"dateModified\":\"2024-01-30T09:31:32+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#webpage\"},\"articleSection\":\"Blog, Farmaci\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#listItem\",\"name\":\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#listItem\",\"position\":3,\"name\":\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/\",\"name\":\"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project\",\"description\":\"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l'assunzione\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/farmaci-acidita-di-stomaco.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#mainImage\",\"width\":400,\"height\":334},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/01\\\/03\\\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\\\/#mainImage\"},\"datePublished\":\"2018-01-03T20:26:37+01:00\",\"dateModified\":\"2024-01-30T09:31:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project","description":"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l'assunzione","canonical_url":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#blogposting","name":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project","headline":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!","author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/farmaci-acidita-di-stomaco.jpg","width":400,"height":334},"datePublished":"2018-01-03T20:26:37+01:00","dateModified":"2024-01-30T09:31:32+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#webpage"},"articleSection":"Blog, Farmaci"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/en\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#listItem","name":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#listItem","position":3,"name":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/en\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#webpage","url":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/","name":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project","description":"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l'assunzione","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/farmaci-acidita-di-stomaco.jpg","@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#mainImage","width":400,"height":334},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/#mainImage"},"datePublished":"2018-01-03T20:26:37+01:00","dateModified":"2024-01-30T09:31:32+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/en\/#website","url":"https:\/\/toplifeproject.com\/en\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"en-US","publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project","og:description":"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l'assunzione","og:url":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2018-01-03T19:26:37+00:00","article:modified_time":"2024-01-30T08:31:32+00:00","twitter:card":"summary_large_image","twitter:title":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!! - Top Life Project","twitter:description":"Meglio noti soprattutto gli inibitori di pompa protonica (PPI) come Nexium, Pantorc, Pantopan, Lansox, o i loro generici pantoprazolo, esomeprazolo, omeprazolo, etc I gastroprotettori sono tra i farmaci pi\u00f9 utilizzati in Italia, ma presentano gravi effetti collaterali. I gastroprotettori assunti su base cronica possono causare una carenza di vitamina B12, dovuta al fatto che l'assunzione","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4106","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:35:55","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:14:02","updated":"2026-05-12 21:35:55","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tGASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/en"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/en\/category\/blog\/"},{"label":"GASTROPROTETTORI: ATTENTI A NON ASSUMERLI TROPPO A LUNGO!!!!","link":"https:\/\/toplifeproject.com\/en\/2018\/01\/03\/gastroprotettori-attenti-a-non-assumerli-troppo-a-lungo\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 23:23:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/comments?post=4106"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media\/4107"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media?parent=4106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/categories?post=4106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/tags?post=4106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}