{"id":4131,"date":"2018-02-18T15:09:48","date_gmt":"2018-02-18T14:09:48","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4131"},"modified":"2024-01-30T09:31:32","modified_gmt":"2024-01-30T08:31:32","slug":"come-perdere-20-kg-e-sistemare-il-metabolismo","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/","title":{"rendered":"Come perdere 20 kg e sistemare il metabolismo"},"content":{"rendered":"<p>Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9.<\/p>\n<p>Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E&#8217; possibile. Ma sicuramente il dogma &#8220;mangia meno e muoviti di pi\u00f9&#8221; non regge nel <a href=\"https:\/\/endriutec.it\/cristinatomasi\/wp-content\/uploads\/2018\/02\/classificazione-obesita-secondo-indice-di-massa-corporea.gif\"><img decoding=\"async\" class=\"lazyload size-medium wp-image-14094 alignleft\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27227%27%20viewBox%3D%270%200%20300%20227%27%3E%3Crect%20width%3D%27300%27%20height%3D%27227%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/endriutec.it\/cristinatomasi\/wp-content\/uploads\/2018\/02\/classificazione-obesita-secondo-indice-di-massa-corporea-300x227.gif\" alt=\"\" width=\"300\" height=\"227\" \/><\/a>lungo termine. Quanti di voi dopo aver perso qualche kg hanno raggiunto un plateau di peso dal quale non si sono pi\u00f9 schiodati? Contare le calorie, fare attivit\u00e0 fisica per ore, ignorare la fame non vi porta da nessuna parte: vi torturate e frustrate per niente! E poi lasciate perdere. IL risultato \u00e8 l&#8217;epidemia di obesit\u00e0 che abbiamo purtroppo a livello mondiale.<\/p>\n<p>Dobbiamo affrontare l&#8217;obesit\u00e0 consci che si tratta di un problema ormonale: dobbiamo ridurre l&#8217;attivit\u00e0 dell&#8217;insulina, l&#8217;ormone che immagazzina il grasso; solo cos\u00ec riuscirete a perdere il grasso in eccesso.<\/p>\n<p>Perdere peso e mantenere l&#8217;obiettivo raggiunto, mettendo a posto tutti i parametri metabolici prima <a href=\"https:\/\/endriutec.it\/cristinatomasi\/wp-content\/uploads\/2018\/02\/insulinoresistenza.jpg\"><img decoding=\"async\" class=\"lazyload size-medium wp-image-14095 alignright\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27173%27%20viewBox%3D%270%200%20300%20173%27%3E%3Crect%20width%3D%27300%27%20height%3D%27173%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/endriutec.it\/cristinatomasi\/wp-content\/uploads\/2018\/02\/insulinoresistenza-300x173.jpg\" alt=\"\" width=\"300\" height=\"173\" \/><\/a>&#8220;scassati&#8221; dovrebbe essere il primo approccio all&#8217;obesit\u00e0, condito con una buona dose di forza di volont\u00e0.<\/p>\n<p>Questa mia paziente ha perso oltre 20 kg, di cui una parte velocemente con la MAP-diet, seguita da una dieta LCHF, con la quale mantiene benissimo il peso raggiunto. In passato aveva provato molte diete. Da anni mangiava piccole quantit\u00e0. Ma di cibo sbagliato.<\/p>\n<p>Ottimizzazione dei valori ematici metabolici.<\/p>\n<p>Benessere psico-fisico.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Tutto quello che vi hanno insegnato in merito al calo<\/p>","protected":false},"author":3,"featured_media":4133,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,72,77,75,78,79],"tags":[],"class_list":["post-4131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentazione","category-blog","category-dieta","category-map","category-metabolismo","category-obesita"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E&#039; possibile. Ma sicuramente il dogma &quot;mangia meno e muoviti di pi\u00f9&quot; non regge\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Come perdere 20 kg e sistemare il metabolismo - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E&#039; possibile. Ma sicuramente il dogma &quot;mangia meno e muoviti di pi\u00f9&quot; non regge\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-02-18T14:09:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Come perdere 20 kg e sistemare il metabolismo - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E&#039; possibile. Ma sicuramente il dogma &quot;mangia meno e muoviti di pi\u00f9&quot; non regge\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#blogposting\",\"name\":\"Come perdere 20 kg e sistemare il metabolismo - Top Life Project\",\"headline\":\"Come perdere 20 kg e sistemare il metabolismo\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_8804-1-scaled-1.jpg\",\"width\":2560,\"height\":2560},\"datePublished\":\"2018-02-18T15:09:48+01:00\",\"dateModified\":\"2024-01-30T09:31:32+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#webpage\"},\"articleSection\":\"Alimentazione, Blog, Dieta, MAP, Metabolismo, Obesit\\u00e0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#listItem\",\"name\":\"Come perdere 20 kg e sistemare il metabolismo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#listItem\",\"position\":3,\"name\":\"Come perdere 20 kg e sistemare il metabolismo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/\",\"name\":\"Come perdere 20 kg e sistemare il metabolismo - Top Life Project\",\"description\":\"Tutto quello che vi hanno insegnato in merito al calo ponderale \\u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E' possibile. Ma sicuramente il dogma \\\"mangia meno e muoviti di pi\\u00f9\\\" non regge\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_8804-1-scaled-1.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#mainImage\",\"width\":2560,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2018\\\/02\\\/18\\\/come-perdere-20-kg-e-sistemare-il-metabolismo\\\/#mainImage\"},\"datePublished\":\"2018-02-18T15:09:48+01:00\",\"dateModified\":\"2024-01-30T09:31:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Come perdere 20 kg e sistemare il metabolismo - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"Come perdere 20 kg e sistemare il metabolismo - Top Life Project","description":"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E' possibile. Ma sicuramente il dogma \"mangia meno e muoviti di pi\u00f9\" non regge","canonical_url":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#blogposting","name":"Come perdere 20 kg e sistemare il metabolismo - Top Life Project","headline":"Come perdere 20 kg e sistemare il metabolismo","author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/IMG_8804-1-scaled-1.jpg","width":2560,"height":2560},"datePublished":"2018-02-18T15:09:48+01:00","dateModified":"2024-01-30T09:31:32+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#webpage"},"articleSection":"Alimentazione, Blog, Dieta, MAP, Metabolismo, Obesit\u00e0"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/en\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#listItem","name":"Come perdere 20 kg e sistemare il metabolismo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#listItem","position":3,"name":"Come perdere 20 kg e sistemare il metabolismo","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/en\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#webpage","url":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/","name":"Come perdere 20 kg e sistemare il metabolismo - Top Life Project","description":"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E' possibile. Ma sicuramente il dogma \"mangia meno e muoviti di pi\u00f9\" non regge","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/IMG_8804-1-scaled-1.jpg","@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#mainImage","width":2560,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/#mainImage"},"datePublished":"2018-02-18T15:09:48+01:00","dateModified":"2024-01-30T09:31:32+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/en\/#website","url":"https:\/\/toplifeproject.com\/en\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"en-US","publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"Come perdere 20 kg e sistemare il metabolismo - Top Life Project","og:description":"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E' possibile. Ma sicuramente il dogma &quot;mangia meno e muoviti di pi\u00f9&quot; non regge","og:url":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2018-02-18T14:09:48+00:00","article:modified_time":"2024-01-30T08:31:32+00:00","twitter:card":"summary_large_image","twitter:title":"Come perdere 20 kg e sistemare il metabolismo - Top Life Project","twitter:description":"Tutto quello che vi hanno insegnato in merito al calo ponderale \u00e8 sbagliato: non si tratta di tagliare le calorie e muoversi di pi\u00f9. Sono molti a non riuscire a perdere peso, sebbene mangino poco. Vorreste dimagrire velocemente e non riuscite? E' possibile. Ma sicuramente il dogma &quot;mangia meno e muoviti di pi\u00f9&quot; non regge","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4131","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:39:28","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:14:02","updated":"2026-05-12 21:39:28","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tCome perdere 20 kg e sistemare il metabolismo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/en"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/en\/category\/blog\/"},{"label":"Come perdere 20 kg e sistemare il metabolismo","link":"https:\/\/toplifeproject.com\/en\/2018\/02\/18\/come-perdere-20-kg-e-sistemare-il-metabolismo\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:10:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/comments?post=4131"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media\/4133"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media?parent=4131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/categories?post=4131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/tags?post=4131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}