{"id":4677,"date":"2015-12-05T22:32:43","date_gmt":"2015-12-05T21:32:43","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4677"},"modified":"2024-01-30T09:31:33","modified_gmt":"2024-01-30T08:31:33","slug":"la-soia","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/","title":{"rendered":"LA SOIA"},"content":{"rendered":"<p>La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di soia e quant&#8217;altro, prodotti che stanno pericolosamente trovando sempre pi\u00f9 spazio nei carrelli delle famiglie italiane.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Io sono preoccupata perch\u00e9 molte persone comprano prodotti a base di soja, frutto di elaborazioni industriali.<\/strong><\/span> Il tutto \u00e8 tratto dal <span style=\"color: #0000ff;\"><strong>libro di Kayyla Daniel &#8220;The whole truth about soy&#8221;<\/strong><\/span>, che vi consiglio di leggere.<\/p>\n<p>La soia \u00e8 diffusissima, dal latte, allo yogurt al tofu ai fagioli. Eppure questi alimenti non sono benefici per la salute come vedrete di seguito. In Oriente infatti la soia non viene consumata cos\u00ec ma nell\u2019antichit\u00e0 solo la soia fermentata faceva parte della dieta ed infatti \u00e8 benefica per il corpo ed ha nutrito gli asiatici per millenni. La fermentazione distrugge le tossine e antinutrienti presenti producendo invece nutrienti biodisponibili. La soia, cos\u00ec com\u2019\u00e8, contiene sostanze che sono tossiche per l\u2019uomo. \u00c8 per questo che la soja non fermentata pu\u00f2 causare gravi problemi di salute, come il cancro al seno, disturbi della tiroide, danni cerebrali, calcoli renali, allergie alimentari, e altro ancora.<br \/>\nIl Dr. Joseph Mercola ha stilato i 9 punti principali per cui la soia \u00e8 dannosa per l\u2019uomo:<\/p>\n<p><span style=\"color: #ff0000;\"><strong>1. La maggior parte della soia in commercio \u00e8 geneticamente modificata<\/strong>.<\/span> La modificazione genetica taglia i costi e aumenta la produttivit\u00e0, ma a scapito degli erbicidi tossici spruzzati, come il glifosato, un noto cancerogeno. La soia geneticamente modificata ha anche un DNA che produce una proteina estranea al corpo umano con effetti potenzialmente devastanti.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>2. Come gli altri OGM, la soia provoca allergie.<\/strong><\/span> Secondo uno studio sugli esseri umani nutriti con alimenti geneticamente modificati, il gene della soia OGM viene trasmesso nei nostri batteri intestinali e il suo DNA continua a funzionare. Anche se si smette di mangiare soia OGM per anni, \u00e8 ancora possibile ottenere una proteina potenzialmente allergizzante che il nostro intestino continua a produrre. La soia OGM pu\u00f2 anche causare infertilit\u00e0, come riporta una ricerca russa. Studi sui ratti hanno osservato che i danni degli OGM si trasmettono principalmente alla seconda e terza generazione tanto che la terza generazione \u00e8 sterile.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>3. La soia contiene tossine naturalichiamate anti-nutrienti.<\/strong><\/span> I composti antinutrizionali presenti nella soia sono: soiatossina (una nuova tossina recentemente trovata nella soia), saponine, fitati, pxalati, inibitori della proteasi, gli estrogeni, e goitrogeni. Queste sostanze interferiscono con i nostri enzimi digestivi, sottraggonominerali essenziali al corpo, aumentano la permeabilit\u00e0 intestinale, rallentano latiroide producendo un malessere diffuso nel corpo.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>4. La soia pu\u00f2 causare coaguli di sangue pericolosi.<\/strong> <\/span>L\u2019emoagglutinina \u00e8 una sostanza che stimola i globuli rossi a raggrupparsi. Questi coaguli di globuli rossi non possono assorbire e distribuire l\u2019ossigeno correttamente ai tessuti.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>5. La soia disturba il corretto funzionamento della tiroide.<\/strong><\/span> I goitrogeni, sostanze che si trovano nella soia, interferiscono con il metabolismo dello iodio e causano disturbi alla tiroide ostacolando la sintesi degli ormoni tiroidei. Causando quindi stanchezza, debolezza e danni al sistema ormonale.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>6. La soia sottrae i minerali.<\/strong><\/span> I fitati, o acido fitico, si attaccano ai minerali impedendone l\u2019assorbimento, come magnesio, calcio, zinco e ferro. Questi minerali sono indispensabili per il funzionamento delle reazioni chimiche che avvengono continuamente nel corpo. Gli effetti sono danni alle ossa, ai denti, capelli, disturbi del sonno, umore, annebbiamento mentale, debolezza e molto altro. E\u2019 infatti risaputo che integrando ad esempio il magnesio si hanno tantissimi benefici a livello di salute, e lo stesso vale per lo zinco, il ferro e gli alti minerali. Quindi piutosto che prendere degli integratori cerchiamo di non farceli sottrarre.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>7. La soia contiene dei fitoestrogeni.<\/strong><\/span> Sono dei composti vegetali simili agli estrogeni umani. Questi composti imitano e talvolta ostacolano gli estrogeni. Hanno effetti negativi su diversi organi umani. I fitoestrogeni della soia disturbano la funzione endocrina, causano infertilit\u00e0, e possono favorire il cancro al seno.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>8. La soia contiene metalli tossici.<\/strong><\/span> La soia viene trattata in serbatoi in alluminio. Questo provoca il rilascio di alti livelli di alluminio nel prodotto finale.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>9. Il latte di soia pu\u00f2 danneggiare il bambino.<\/strong> <\/span>Gli estrogeni della soia possono danneggiare la salute riproduttiva e lo sviluppo sessuale del bambino.<\/p>\n<h2><span style=\"color: #0000ff;\"><strong>SCEGLI I PRODOTTI FERMENTATI DELLA SOIA<\/strong><\/span><br \/>\n<em>Ecco i derivati fermentati della soia che invece sono benefici. Acquista prodotti biologici e correttamente fermentati della soia:<\/em><\/h2>\n<p><span style=\"color: #0000ff;\"><strong>Miso<\/strong><\/span> \u2013 Comunemente usato nella zuppa di miso, questa pasta di soia fermentata ha propriet\u00e0 antitumorali;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>Natto<\/strong><\/span> \u2013 E\u2019 un cibo fenomenale, ricchissimo della rara Vitamina K2, indispensabile per i denti, ossa, salute del cuore e prevenzione del cancro;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>Tempeh<\/strong> <\/span>\u2013 Questa torta di soia fermentata \u00e8 ricchissima di probiotici che rafforzano il sistema immunitario e la flora batterica;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>Salsa di soia<\/strong><\/span> \u2013 E&#8217; tradizionalmente fatta da soia fermentata, sale ed enzimi. Comunemente chiamata tamari, ma assicurati di aver scelto un marchio biologico naturale e non quelle fatte artificialmente attraverso processi chimici.<\/p>\n<h2><span style=\"color: #800000;\"><strong>E GLI ASIATICI?<\/strong><\/span><\/h2>\n<h4>La coltivazione di soia \u00e8 iniziata intorno al 1100 aC in Cina, dove \u00e8 stato utilizzata per fertilizzare i terreni e come mangime per gli animali. I fagioli di soia non erano considerati idonei per l\u2019uomo fino a quando i cinesi hanno imparato a fermentarli, un processo che li rende digeribili. Le diete asiatiche ora includono i fagioli di soia fermentati in forma di natto, il miso, tamari, e tempeh.<br \/>\nI produttori di soia (un business enorme tanto da aver contrastato e rallentato il consumo di olio di oliva, di cocco e altri prodotti benefici) vogliono che tu mangi pi\u00f9 soia. Devi sapere che i giapponesi e cinesi mangiano 10 grammi di soia al giorno \u2013 circa due cucchiaini! Eppure, un produttore di soia (che ha influenzato anche le linee guida alimentare e gli studi scientifici) B quello che i giapponesi mangiano, ovvero 100 grammi di proteine di soia al giorno.<br \/>\nIl tofu non \u00e8 consigliato, in quanto non \u00e8 fermentato. Molti notano che cominciando a consumare latte di soia hanno dei fastidi e smettendo questi scompaiono. A rischio sono soprattutto i vegani che consumano molto tofu e prodotti a base di soia con l\u2019obiettivo di avere delle proteine. Ebbene ora sappiamo quali sono i danni della soia non fermentata.<\/h4>","protected":false},"excerpt":{"rendered":"<p>La soia che noi conosciamo ha molto poco in comune<\/p>","protected":false},"author":3,"featured_media":4570,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,72,77,78,79],"tags":[285],"class_list":["post-4677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentazione","category-blog","category-dieta","category-metabolismo","category-obesita","tag-soia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"LA SOIA - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-05T21:32:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"LA SOIA - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#blogposting\",\"name\":\"LA SOIA - Top Life Project\",\"headline\":\"LA SOIA\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/soja-beneficios.jpg\",\"width\":600,\"height\":413},\"datePublished\":\"2015-12-05T22:32:43+01:00\",\"dateModified\":\"2024-01-30T09:31:33+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#webpage\"},\"articleSection\":\"Alimentazione, Blog, Dieta, Metabolismo, Obesit\\u00e0, soia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#listItem\",\"name\":\"LA SOIA\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#listItem\",\"position\":3,\"name\":\"LA SOIA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/\",\"name\":\"LA SOIA - Top Life Project\",\"description\":\"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/soja-beneficios.jpg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#mainImage\",\"width\":600,\"height\":413},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2015\\\/12\\\/05\\\/la-soia\\\/#mainImage\"},\"datePublished\":\"2015-12-05T22:32:43+01:00\",\"dateModified\":\"2024-01-30T09:31:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>LA SOIA - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"LA SOIA - Top Life Project","description":"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di","canonical_url":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#blogposting","name":"LA SOIA - Top Life Project","headline":"LA SOIA","author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/soja-beneficios.jpg","width":600,"height":413},"datePublished":"2015-12-05T22:32:43+01:00","dateModified":"2024-01-30T09:31:33+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#webpage"},"articleSection":"Alimentazione, Blog, Dieta, Metabolismo, Obesit\u00e0, soia"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/toplifeproject.com\/en\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#listItem","name":"LA SOIA"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#listItem","position":3,"name":"LA SOIA","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/en\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#webpage","url":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/","name":"LA SOIA - Top Life Project","description":"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/soja-beneficios.jpg","@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#mainImage","width":600,"height":413},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/#mainImage"},"datePublished":"2015-12-05T22:32:43+01:00","dateModified":"2024-01-30T09:31:33+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/en\/#website","url":"https:\/\/toplifeproject.com\/en\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"en-US","publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"LA SOIA - Top Life Project","og:description":"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di","og:url":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2015-12-05T21:32:43+00:00","article:modified_time":"2024-01-30T08:31:33+00:00","twitter:card":"summary_large_image","twitter:title":"LA SOIA - Top Life Project","twitter:description":"La soia che noi conosciamo ha molto poco in comune con a soia che viene consumata tradizionalmente nei paesi orientali, dove mangiano notoriamente soja fermentata come miso, tempeh e natto. Quindi, nulla in comune con le schifezze che ci vengono propinate sotto forma di jogurt di soia, latte di soia, formaggio di soia, farina di","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4677","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:30:06","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:10:08","updated":"2026-05-12 21:30:06","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tLA SOIA\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/en"},{"label":"Blog","link":"https:\/\/toplifeproject.com\/en\/category\/blog\/"},{"label":"LA SOIA","link":"https:\/\/toplifeproject.com\/en\/2015\/12\/05\/la-soia\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 21:10:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/comments?post=4677"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media\/4570"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media?parent=4677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/categories?post=4677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/tags?post=4677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}