{"id":4876,"date":"2021-05-21T15:17:46","date_gmt":"2021-05-21T13:17:46","guid":{"rendered":"https:\/\/toplifeproject.com\/?p=4876"},"modified":"2024-01-30T09:31:30","modified_gmt":"2024-01-30T08:31:30","slug":"diabete-mellito-storie-cliniche","status":"publish","type":"post","link":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/","title":{"rendered":"DIABETE MELLITO: storie cliniche"},"content":{"rendered":"<h2><span style=\"color: #ff0000;\"><strong>Justin Nolan, affetto da DM tipo 1<\/strong><\/span><\/h2>\n<h4><span style=\"color: #000000;\"><strong>Guarda la sua pagina FB Tame Type 1<\/strong><\/span><\/h4>\n<p><span style=\"color: #000000;\">Eccovi la sua storia:<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8220;Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW CARB fino a circa 3 anni fa. Non ho mai incontrato il Dr. Bernstein, ma RD Dikeman mi ha mandato un messaggio e mi ha detto del suo lavoro, ha condiviso alcuni dei suoi video su youtube, e mi ha fatto fare clic! Sta mangiando low &#8211; carb da allora.<\/span><\/p>\n<p><span style=\"color: #000000;\">Appena ricevuta la diagnosi di diabete, il mio medico mi ha detto che potevo mangiare quello che volevo, purch\u00e9 facessi l&#8217;insulina. E cos\u00ec, da bambino, ho fatto esattamente questo. I risultati sono stati disastrosi. Le mie glicemie erano sulle montagne russe (da molto alte a molto basse) e ci\u00f2 ha frenato la mia crescita, ho ridotto la mia memoria ed ha causato danni incalcolabili dovuti a valori di glicemia costantemente elevati.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ho lottato fino al punto di arrendermi, fino al punto di avere pensieri suicidi e una depressione devastante. E, peggio ancora, i medici non mi hanno dato consigli utili. Ho perso ogni speranza, convinto che sarei morto prima dei 40 anni senza piedi e senza occhi. Sono caduto sempre pi\u00f9 in disperazione, fino a quando ho scoperto il dottor Bernstein e l&#8217;approccio low-carb qualche anno fa.<\/span><\/p>\n<p><span style=\"color: #000000;\">Il pensiero di eliminare i carboidrati non mi aveva mai sfiorato e nessun medico me lo aveva mai detto.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ma aveva assolutamente senso!<\/span><\/p>\n<p><span style=\"color: #000000;\">E, dopo aver eliminato tutto il cibo spazzatura e seguendo una rigida low-carb, a base di carne, i miei valori di glicemia sono migliorati drammaticamente, senza il minimo sforzo! Era come un miracolo. Il fardello di un destino funesto mi \u00e8 stato tolto, e mi sono reso conto che in realt\u00e0 posso avere valori glicemici normali e sani.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ha cambiato la mia vita per sempre.&#8221;<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #ff0000;\"><strong>La testimonianza di Giusy e di sua madre, affetta da diabete tipo 2<\/strong><\/span><\/h2>\n<p><span style=\"color: #000000;\">Mia madre \u00e8 diabetica da ben 40anni e le \u00e8 sempre stata consigliata una dieta con colazione con pane o fette biscottate, pranzo con pasta e spuntino con biscotti e cena con pane &#8230; in piccole dosi ma era essenziale mangiare sempre carboidrati &#8230; lei faceva tre insuline al giorno pi\u00f9 tre pastiglie &#8230; \u00e8 divenuta cieca per retinopatia diabetica<\/span><\/p>\n<p><span style=\"color: #000000;\">da tre anni a questa parte la sto seguendo personalmente e le ho tolto completamente pane, pasta, pizza biscotti, frutta, dandole solo proteine verdure, ovviamente non sto a dirvi: \u00a0tutti contro perch\u00e9 non era giusto, stavo sbagliando ecc &#8230;<\/span><\/p>\n<p><span style=\"color: #000000;\">Il risultato \u00e8 che mia madre non fa pi\u00f9 l&#8217;insulina, non prende pi\u00f9 le pastiglie per il diabete e nemmeno quella per la pressione!<\/span><\/p>\n<p><span style=\"color: #000000;\">Sta benissimo per fortuna con esami e glicate perfetti: questa \u00e8 la mia esperienza ma ovviamente farlo capire \u00e8 ancora un enorme problema, purtroppo<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #ff0000;\"><strong>Storia clinica: diabete tipo 2 e obesit\u00e0<\/strong><\/span><\/h2>\n<p><span style=\"color: #000000;\">Karl, 56 anni<\/span><\/p>\n<p><span style=\"color: #000000;\">Marzo: Peso 138 kg e 1.88 M<\/span><\/p>\n<p><span style=\"color: #000000;\">Iperteso (Bivis e bisoprololo)<\/span><\/p>\n<p><span style=\"color: #000000;\">Diabetico (Metformina 1000 x 3 e Januvia)<\/span><\/p>\n<p><span style=\"color: #000000;\">Ipovitaminosi D, B12 e B9<\/span><\/p>\n<p><span style=\"color: #000000;\">iperomocisteinemia<\/span><\/p>\n<p><span style=\"color: #000000;\">Alimentazione: prevalentemente basata su cereali in tutte le forme<\/span><\/p>\n<p><span style=\"color: #000000;\">Inizio aprile: inizia alimentazione LOW CARB e si muove su base regolare<\/span><\/p>\n<p><span style=\"color: #000000;\">Maggio: sospeso Januvia, ridotto Metformina a 2 compresse al giorno. Ridotta terapia antipertensiva<\/span><\/p>\n<p><span style=\"color: #000000;\">Peso 120 kg<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">IL POTERE di cosa mangiamo<\/span><\/p>\n<h2 style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">NEL DIABETE COMUNQUE ASSOLUTAMENTE <\/span><\/strong><\/h2>\n<h2 style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">LOW CARB<\/span><\/strong><\/h2>","protected":false},"excerpt":{"rendered":"<p>Justin Nolan, affetto da DM tipo 1 Guarda la sua<\/p>","protected":false},"author":3,"featured_media":4347,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,95,77,78,96],"tags":[109,108,111,116,114,115],"class_list":["post-4876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentazione","category-carboidrati","category-dieta","category-metabolismo","category-zucchero","tag-diabete-tipo-2","tag-insulinoresistenza","tag-low-carb","tag-metformina","tag-obesita","tag-sovrappeso"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: &quot;Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cristina Tomasi\"\/>\n\t<meta name=\"google-site-verification\" content=\"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Top Life Project - Prendi in mano la tua salute\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"DIABETE MELLITO: storie cliniche - Top Life Project\" \/>\n\t\t<meta property=\"og:description\" content=\"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: &quot;Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-05-21T13:17:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-30T08:31:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"DIABETE MELLITO: storie cliniche - Top Life Project\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: &quot;Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#blogposting\",\"name\":\"DIABETE MELLITO: storie cliniche - Top Life Project\",\"headline\":\"DIABETE MELLITO: storie cliniche\",\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/sugar-5965359_1920.jpeg\",\"width\":1920,\"height\":1280},\"datePublished\":\"2021-05-21T15:17:46+02:00\",\"dateModified\":\"2024-01-30T09:31:30+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#webpage\"},\"articleSection\":\"Alimentazione, Carboidrati, Dieta, Metabolismo, Zucchero, diabete tipo 2, insulinoresistenza, low carb, metformina, obesit\\u00e0, sovrappeso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/alimentazione\\\/#listItem\",\"name\":\"Alimentazione\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/alimentazione\\\/#listItem\",\"position\":2,\"name\":\"Alimentazione\",\"item\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/alimentazione\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#listItem\",\"name\":\"DIABETE MELLITO: storie cliniche\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#listItem\",\"position\":3,\"name\":\"DIABETE MELLITO: storie cliniche\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/category\\\/alimentazione\\\/#listItem\",\"name\":\"Alimentazione\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo2.svg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#organizationLogo\",\"width\":8178,\"height\":2639},\"image\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/\",\"name\":\"Cristina Tomasi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cristina Tomasi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#webpage\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/\",\"name\":\"DIABETE MELLITO: storie cliniche - Top Life Project\",\"description\":\"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: \\\"Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/author\\\/criamdtpl-2\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/sugar-5965359_1920.jpeg\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#mainImage\",\"width\":1920,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/2021\\\/05\\\/21\\\/diabete-mellito-storie-cliniche\\\/#mainImage\"},\"datePublished\":\"2021-05-21T15:17:46+02:00\",\"dateModified\":\"2024-01-30T09:31:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/\",\"name\":\"Top Life Project S.r.l.\",\"description\":\"Prendi in mano la tua salute\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/toplifeproject.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>DIABETE MELLITO: storie cliniche - Top Life Project<\/title>\n\n","aioseo_head_json":{"title":"DIABETE MELLITO: storie cliniche - Top Life Project","description":"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: \"Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW","canonical_url":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"i-A-FjKIbeGJjnqzisq-ZFPG85apRPfuPaFaxPbaeZY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#blogposting","name":"DIABETE MELLITO: storie cliniche - Top Life Project","headline":"DIABETE MELLITO: storie cliniche","author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/sugar-5965359_1920.jpeg","width":1920,"height":1280},"datePublished":"2021-05-21T15:17:46+02:00","dateModified":"2024-01-30T09:31:30+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#webpage"},"isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#webpage"},"articleSection":"Alimentazione, Carboidrati, Dieta, Metabolismo, Zucchero, diabete tipo 2, insulinoresistenza, low carb, metformina, obesit\u00e0, sovrappeso"},{"@type":"BreadcrumbList","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/toplifeproject.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/alimentazione\/#listItem","name":"Alimentazione"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/alimentazione\/#listItem","position":2,"name":"Alimentazione","item":"https:\/\/toplifeproject.com\/en\/category\/alimentazione\/","nextItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#listItem","name":"DIABETE MELLITO: storie cliniche"},"previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#listItem","position":3,"name":"DIABETE MELLITO: storie cliniche","previousItem":{"@type":"ListItem","@id":"https:\/\/toplifeproject.com\/en\/category\/alimentazione\/#listItem","name":"Alimentazione"}}]},{"@type":"Organization","@id":"https:\/\/toplifeproject.com\/en\/#organization","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","url":"https:\/\/toplifeproject.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2025\/09\/logo2.svg","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#organizationLogo","width":8178,"height":2639},"image":{"@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author","url":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/","name":"Cristina Tomasi","image":{"@type":"ImageObject","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e410b0f14ed32466620669550e4d2a380ba796fb9526466b3dc71e9cf68868ad?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cristina Tomasi"}},{"@type":"WebPage","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#webpage","url":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/","name":"DIABETE MELLITO: storie cliniche - Top Life Project","description":"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: \"Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/toplifeproject.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#breadcrumblist"},"author":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"creator":{"@id":"https:\/\/toplifeproject.com\/en\/author\/criamdtpl-2\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2023\/02\/sugar-5965359_1920.jpeg","@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#mainImage","width":1920,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/#mainImage"},"datePublished":"2021-05-21T15:17:46+02:00","dateModified":"2024-01-30T09:31:30+01:00"},{"@type":"WebSite","@id":"https:\/\/toplifeproject.com\/en\/#website","url":"https:\/\/toplifeproject.com\/en\/","name":"Top Life Project S.r.l.","description":"Prendi in mano la tua salute","inLanguage":"en-US","publisher":{"@id":"https:\/\/toplifeproject.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Top Life Project - Prendi in mano la tua salute","og:type":"article","og:title":"DIABETE MELLITO: storie cliniche - Top Life Project","og:description":"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: &quot;Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW","og:url":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/","og:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:secure_url":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg","og:image:width":1200,"og:image:height":628,"article:published_time":"2021-05-21T13:17:46+00:00","article:modified_time":"2024-01-30T08:31:30+00:00","twitter:card":"summary_large_image","twitter:title":"DIABETE MELLITO: storie cliniche - Top Life Project","twitter:description":"Justin Nolan, affetto da DM tipo 1 Guarda la sua pagina FB Tame Type 1 Eccovi la sua storia: &quot;Mi chiamo Justin Nolan e sono diabetico di tipo 1 da oltre 14 anni. Mi hanno diagnosticato il diabete tipo 1 nel luglio 2005 a 10 anni. E non ho mai sentito parlare di dieta LOW","twitter:image":"https:\/\/toplifeproject.com\/wp-content\/uploads\/2026\/08\/logo2-1.jpg"},"aioseo_meta_data":{"post_id":"4876","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 22:02:05","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-05-11 14:21:03","updated":"2026-05-12 22:02:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/toplifeproject.com\/en\/category\/alimentazione\/\" title=\"Alimentazione\">Alimentazione<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tDIABETE MELLITO: storie cliniche\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/toplifeproject.com\/en"},{"label":"Alimentazione","link":"https:\/\/toplifeproject.com\/en\/category\/alimentazione\/"},{"label":"DIABETE MELLITO: storie cliniche","link":"https:\/\/toplifeproject.com\/en\/2021\/05\/21\/diabete-mellito-storie-cliniche\/"}],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:14:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/comments?post=4876"}],"version-history":[{"count":0,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/posts\/4876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media\/4347"}],"wp:attachment":[{"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/media?parent=4876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/categories?post=4876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toplifeproject.com\/en\/wp-json\/wp\/v2\/tags?post=4876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}